{"id":16,"date":"2019-12-05T05:42:57","date_gmt":"2019-12-05T05:42:57","guid":{"rendered":"https:\/\/promo-theme.com\/plaxer\/?page_id=16"},"modified":"2021-01-08T10:47:50","modified_gmt":"2021-01-08T10:47:50","slug":"about-me","status":"publish","type":"page","link":"https:\/\/thekarzu.com\/es\/about-me\/","title":{"rendered":"About Me"},"content":{"rendered":"<section class=\"wpb-content-wrapper\"><div class=\"vc_row wpb_row vc_row-fluid vc_row-5def67accc99a vc_row-o-content-middle vc_row-flex\">\n    \n    <div class=\"wpb_column vc_column_container vc_col-sm-6 vc_column_container-5def697eeb071\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">      <div class=\"side-img-block side-img-block-5def68439682a\" style=\"background-image: url(https:\/\/i0.wp.com\/thekarzu.com\/wp-content\/uploads\/2020\/12\/theKarzu-Facicon-scaled.jpg?fit=1024%2C724&#038;ssl=1);\"><\/div>\n    <\/div><\/div><\/div>\n    \n    <div class=\"wpb_column vc_column_container vc_col-sm-6 vc_column_container-5def699cc0a07\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">    <div class=\"tabs-block tabs-block-6a0492ab8b1be\">\r\n      <div class=\"tb-buttons\">\r\n                  <div class=\"button\" data-magic-cursor=\"link-small\" data-title=\"About\">About<\/div>\r\n                  <div class=\"button\" data-magic-cursor=\"link-small\" data-title=\"Shedule\">Shedule<\/div>\r\n              <\/div>\r\n      <div class=\"tb-wrap\">\r\n            <div class=\"wrap\">\r\n      <div class=\"tb-m-button\">About<\/div>\r\n      <div class=\"wrap-inner\">\r\n              <div class=\"heading-block heading-5df867a29f1bd tal h-h5\">\n                  <h5 class=\"h\"><span>Thanks<\/span> for stopping by.<\/h5>\n              <\/div>\n    \n\t<div class=\"wpb_text_column wpb_content_element  text-t1 wpb_text_column-5def687f564d4\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>Hey, i&#8217;m Moses, yeah like the bible (no i don&#8217;t have a staff), and I&#8217;m a gamer. Thanks for stopping by my blog.<\/p>\n<p>If you enjoy talking about games, sharing your opinions, getting into debates, or just bragging about your gamer wins (yes, I know they are awesome) then I think you will love it here.<\/p>\n<p>My goal is to have this community grow with me. So there will be constant updates and I will keep improving on what the website is right now. So feel free to stop by often.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n      <\/div>\r\n    <\/div>\r\n        <div class=\"wrap\">\r\n      <div class=\"tb-m-button\">Shedule<\/div>\r\n      <div class=\"wrap-inner\">\r\n              <div class=\"heading-block heading-5f5552492b923 tal h-h5\">\n                  <h5 class=\"h\">How often do you post and when do you stream?<\/h5>\n              <\/div>\n    \n\t<div class=\"wpb_text_column wpb_content_element  text-t1 wpb_text_column-5f555273f71eb\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>I post at least 2-3 times a week. I love to switch things up and introduce new ideas so the topics I write about will always change up and feel fresh, but things will still be all about gaming.<\/p>\n<p>If streaming is your thing and you would like to join the party when I stream, then you can <a href=\"https:\/\/thekarzu.com\/es\/streaming\/\">Join the stream<\/a>\u00a0or catch me on <a href=\"https:\/\/www.twitch.tv\/iamkarzu\" target=\"_blank\" rel=\"noopener\">twitch<\/a>. I stream every day at 9 PM Central.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n      <div class=\"button-container button-5f5554b28ba06 left\">\n        <a class=\"button-style2\" href=\"https:\/\/www.twitch.tv\/iamkarzu\" target=\"_blank\" rel=\"noopener\">\n                    <span>Join the Stream<\/span>\n        <\/a>\n      <\/div>\n          <\/div>\r\n    <\/div>\r\n          <\/div>\r\n    <\/div>\r\n    <\/div><\/div><\/div><\/div>\n    \n    <div class=\"vc_row wpb_row vc_row-fluid vc_row-5dee157a3d61e\">\n    \n    <div class=\"wpb_column vc_column_container vc_col-sm-12 vc_col-lg-offset-1 vc_col-lg-10 vc_column_container-5dee11f37619f\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">    <div class=\"num-box-block num-box-5dee107d64e91  row\">\n          <div class=\"num-box-item num-box-item-5dee108b0d4f6  col-12 col-sm-6 col-md-3\">\n              <div class=\"icon base-icon-twitch\"><\/div>\n            <div class=\"content\">\n        <div class=\"num\">\n          <span class=\"number\">1300<\/span>\n                      <span class=\"suffix\">+<\/span>\n                  <\/div>\n                  <div class=\"title\">twitch streams<\/div>\n              <\/div>\n    <\/div>\n        <div class=\"num-box-item num-box-item-5dee10b730fcc  col-12 col-sm-6 col-md-3\">\n              <div class=\"icon base-icon-youtube-logotype\"><\/div>\n            <div class=\"content\">\n        <div class=\"num\">\n          <span class=\"number\">1100<\/span>\n                      <span class=\"suffix\">+<\/span>\n                  <\/div>\n                  <div class=\"title\">youtube streams<\/div>\n              <\/div>\n    <\/div>\n        <div class=\"num-box-item num-box-item-5dee10d80e988  col-12 col-sm-6 col-md-3\">\n              <div class=\"icon base-icon-playstation\"><\/div>\n            <div class=\"content\">\n        <div class=\"num\">\n          <span class=\"number\">50<\/span>\n                      <span class=\"suffix\">+<\/span>\n                  <\/div>\n                  <div class=\"title\">past games<\/div>\n              <\/div>\n    <\/div>\n        <div class=\"num-box-item num-box-item-5dee10f3c98fc  col-12 col-sm-6 col-md-3\">\n              <div class=\"icon social-icon-twitter-social-logotype\"><\/div>\n            <div class=\"content\">\n        <div class=\"num\">\n          <span class=\"number\">256<\/span>\n                      <span class=\"suffix\">+<\/span>\n                  <\/div>\n                  <div class=\"title\">Twitter followers<\/div>\n              <\/div>\n    <\/div>\n        <\/div>\n    <\/div><\/div><\/div><\/div>\n    \n    <div class=\"vc_row wpb_row vc_row-fluid vc_row-6a0492ab8d6c7\">\n    \n    <div class=\"wpb_column vc_column_container vc_col-sm-12 vc_column_container-6a0492ab8dc20\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">      <div class=\"heading-block heading-6a0492ab8dea0 tal h-h3\">\n                  <h3 class=\"h\">Best moments<\/h3>\n              <\/div>\n    <div class=\"vc_empty_space\"   style=\"height: 64px\"><span class=\"vc_empty_space_inner\"><\/span><\/div>      <div class=\"streams-block filter-block streams-block-5def3aabf04c6\">\n                <div class=\"load-wrap isotope\">\n              <div class=\"stream-item event-box istp-item stream-5def3aca1ae7b category-apex-legends\">\n      <div class=\"wrap\">\n                  <div class=\"image\"><div style=\"background-image: url(https:\/\/i0.wp.com\/thekarzu.com\/wp-content\/uploads\/2020\/09\/m0h1g9bmr2v41.jpg?fit=1920%2C1080&#038;ssl=1);\"><\/div><\/div>\n                <div class=\"content\">\n                      <div class=\"heading\">\n                              <a class=\"link\" href=\"https:\/\/www.youtube.com\/watch?v=0opISR0MfMI\" target=\"_self\" rel=\"noopener\">this is how you close out a game<\/a>\n                          <\/div>\n                      <div class=\"date\">Dec.06.2019 - 02:30 pm<\/div>\n                  <\/div>\n      <\/div>\n              <div class=\"links\">\n                      <a href=\"https:\/\/www.twitch.tv\/guardiaan\" target=\"_self\" class=\"stream-link twitch\" rel=\"noopener\"><i class=\"base-icon-twitch\"><\/i><span>twitch stream<\/span><\/a>\n                  <\/div>\n          <\/div>\n            <\/div>\n              <\/div>\n    <\/div><\/div><\/div><\/div>\n    \n    <div data-vc-full-width=\"true\" data-vc-full-width-init=\"false\" data-vc-stretch-content=\"true\" class=\"vc_row wpb_row vc_row-fluid vc_row-5dee174da9d78 vc_row-no-padding\">\n    \n    <div class=\"wpb_column vc_column_container vc_col-sm-12 vc_column_container-6a0492ab90ba9\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">      <div class=\"heading-block heading-5dee15e25eb52 tac h-h3\">\n                  <h3 class=\"h\">Share with <span>#GGAMER<\/span><\/h3>\n              <\/div>\n        <div class=\"gallery-carousel swiper-container photo-carousel-block-5dee177999b09 popup-gallery\">\n      <div class=\"swiper-wrapper\">\n                  <div class=\"swiper-slide popup-item\" style=\"background-image: url(https:\/\/i0.wp.com\/thekarzu.com\/wp-content\/uploads\/2019\/12\/img52.jpg?fit=300%2C169&#038;ssl=1);\">\n            <a href=\"https:\/\/i0.wp.com\/thekarzu.com\/wp-content\/uploads\/2019\/12\/img52.jpg?fit=2500%2C1406&#038;ssl=1\" data-size=\"2500x1406\" data-id=\"1\"><\/a>\n          <\/div>\n                  <div class=\"swiper-slide popup-item\" style=\"background-image: url(https:\/\/i0.wp.com\/thekarzu.com\/wp-content\/uploads\/2019\/12\/img45.jpg?fit=300%2C218&#038;ssl=1);\">\n            <a href=\"https:\/\/i0.wp.com\/thekarzu.com\/wp-content\/uploads\/2019\/12\/img45.jpg?fit=2500%2C1815&#038;ssl=1\" data-size=\"2500x1815\" data-id=\"2\"><\/a>\n          <\/div>\n                  <div class=\"swiper-slide popup-item\" style=\"background-image: url(https:\/\/i0.wp.com\/thekarzu.com\/wp-content\/uploads\/2019\/12\/img38.jpg?fit=199%2C300&#038;ssl=1);\">\n            <a href=\"https:\/\/i0.wp.com\/thekarzu.com\/wp-content\/uploads\/2019\/12\/img38.jpg?fit=1656%2C2500&#038;ssl=1\" data-size=\"1656x2500\" data-id=\"3\"><\/a>\n          <\/div>\n                  <div class=\"swiper-slide popup-item\" style=\"background-image: url(https:\/\/i0.wp.com\/thekarzu.com\/wp-content\/uploads\/2019\/12\/img40.jpg?fit=225%2C300&#038;ssl=1);\">\n            <a href=\"https:\/\/i0.wp.com\/thekarzu.com\/wp-content\/uploads\/2019\/12\/img40.jpg?fit=1873%2C2500&#038;ssl=1\" data-size=\"1873x2500\" data-id=\"4\"><\/a>\n          <\/div>\n                  <div class=\"swiper-slide popup-item\" style=\"background-image: url(https:\/\/i0.wp.com\/thekarzu.com\/wp-content\/uploads\/2019\/12\/img48.jpg?fit=300%2C293&#038;ssl=1);\">\n            <a href=\"https:\/\/i0.wp.com\/thekarzu.com\/wp-content\/uploads\/2019\/12\/img48.jpg?fit=2500%2C2444&#038;ssl=1\" data-size=\"2500x2444\" data-id=\"5\"><\/a>\n          <\/div>\n                  <div class=\"swiper-slide popup-item\" style=\"background-image: url(https:\/\/i0.wp.com\/thekarzu.com\/wp-content\/uploads\/2019\/12\/img49.jpg?fit=200%2C300&#038;ssl=1);\">\n            <a href=\"https:\/\/i0.wp.com\/thekarzu.com\/wp-content\/uploads\/2019\/12\/img49.jpg?fit=1667%2C2500&#038;ssl=1\" data-size=\"1667x2500\" data-id=\"6\"><\/a>\n          <\/div>\n                  <div class=\"swiper-slide popup-item\" style=\"background-image: url(https:\/\/i0.wp.com\/thekarzu.com\/wp-content\/uploads\/2019\/12\/img43.jpg?fit=300%2C201&#038;ssl=1);\">\n            <a href=\"https:\/\/i0.wp.com\/thekarzu.com\/wp-content\/uploads\/2019\/12\/img43.jpg?fit=2500%2C1674&#038;ssl=1\" data-size=\"2500x1674\" data-id=\"7\"><\/a>\n          <\/div>\n                  <div class=\"swiper-slide popup-item\" style=\"background-image: url(https:\/\/i0.wp.com\/thekarzu.com\/wp-content\/uploads\/2019\/12\/img44.jpg?fit=300%2C201&#038;ssl=1);\">\n            <a href=\"https:\/\/i0.wp.com\/thekarzu.com\/wp-content\/uploads\/2019\/12\/img44.jpg?fit=2500%2C1674&#038;ssl=1\" data-size=\"2500x1674\" data-id=\"8\"><\/a>\n          <\/div>\n                  <div class=\"swiper-slide popup-item\" style=\"background-image: url(https:\/\/i0.wp.com\/thekarzu.com\/wp-content\/uploads\/2019\/12\/img35.jpg?fit=300%2C200&#038;ssl=1);\">\n            <a href=\"https:\/\/i0.wp.com\/thekarzu.com\/wp-content\/uploads\/2019\/12\/img35.jpg?fit=2500%2C1666&#038;ssl=1\" data-size=\"2500x1666\" data-id=\"9\"><\/a>\n          <\/div>\n                  <div class=\"swiper-slide popup-item\" style=\"background-image: url(https:\/\/i0.wp.com\/thekarzu.com\/wp-content\/uploads\/2019\/12\/img36.jpg?fit=300%2C198&#038;ssl=1);\">\n            <a href=\"https:\/\/i0.wp.com\/thekarzu.com\/wp-content\/uploads\/2019\/12\/img36.jpg?fit=2500%2C1652&#038;ssl=1\" data-size=\"2500x1652\" data-id=\"10\"><\/a>\n          <\/div>\n                  <div class=\"swiper-slide popup-item\" style=\"background-image: url(https:\/\/i0.wp.com\/thekarzu.com\/wp-content\/uploads\/2019\/12\/img37.jpg?fit=300%2C200&#038;ssl=1);\">\n            <a href=\"https:\/\/i0.wp.com\/thekarzu.com\/wp-content\/uploads\/2019\/12\/img37.jpg?fit=2500%2C1667&#038;ssl=1\" data-size=\"2500x1667\" data-id=\"11\"><\/a>\n          <\/div>\n              <\/div>\n    <\/div>\n    <\/div><\/div><\/div><\/div><div class=\"vc_row-full-width vc_clearfix\"><\/div>\n<\/section>","protected":false},"excerpt":{"rendered":"<p>About Shedule About Thanks for stopping by. Hey, i&#8217;m Moses, yeah like the bible (no i don&#8217;t have a staff), and I&#8217;m a gamer. Thanks for stopping by my blog. If you enjoy talking about games, sharing your opinions, getting into debates, or just bragging about your gamer wins (yes, I know they are awesome) [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"acf":[],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/thekarzu.com\/es\/wp-json\/wp\/v2\/pages\/16"}],"collection":[{"href":"https:\/\/thekarzu.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/thekarzu.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/thekarzu.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/thekarzu.com\/es\/wp-json\/wp\/v2\/comments?post=16"}],"version-history":[{"count":13,"href":"https:\/\/thekarzu.com\/es\/wp-json\/wp\/v2\/pages\/16\/revisions"}],"predecessor-version":[{"id":3388,"href":"https:\/\/thekarzu.com\/es\/wp-json\/wp\/v2\/pages\/16\/revisions\/3388"}],"wp:attachment":[{"href":"https:\/\/thekarzu.com\/es\/wp-json\/wp\/v2\/media?parent=16"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}